{"id":2130,"date":"2023-03-10T15:21:17","date_gmt":"2023-03-10T14:21:17","guid":{"rendered":"https:\/\/www.grupboix.com\/?p=2130"},"modified":"2026-04-29T14:02:39","modified_gmt":"2026-04-29T12:02:39","slug":"ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet","status":"publish","type":"post","link":"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/","title":{"rendered":"Ampliaci\u00f3n de la planta solar fotovoltaica del centro de producci\u00f3n de Saltet"},"content":{"rendered":"<p><a href=\"https:\/\/www.grupboix.com\/es\/\">Grup Boix<\/a> instala 1.336 paneles fotovoltaicos en el centro de producci\u00f3n del Saltet, Puig-reig, en el marco del proyecto de autoabastecimiento energ\u00e9tico.<\/p>\n<p>El proyecto, financiado por el fondo Next Generation EU dentro del Plan de recuperaci\u00f3n, transformaci\u00f3n y resiliencia, forma parte de la estrategia de la empresa para consumir y producir energ\u00eda 100% renovable. Con una visi\u00f3n ambiciosa, la empresa consolida la segunda fase del proyecto instalando 1.336 paneles que producen una potencia nominal de 440 kWn. Con esto y la primera fase ya realizada, la empresa cuenta con m\u00e1s de 2.000 paneles fotovoltaicos que permiten un ahorro superior a 507.000 kg\/a\u00f1o en emisiones de CO\u2082.<\/p>\n<figure id=\"attachment_1796\" aria-describedby=\"caption-attachment-1796\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1796 size-large\" src=\"https:\/\/www.grupboix.com\/wp-content\/uploads\/2022\/11\/aeria-serradora-boix-e1678457958767-1024x643.jpg\" alt=\"\" width=\"640\" height=\"402\" srcset=\"https:\/\/www.grupboix.com\/wp-content\/uploads\/2022\/11\/aeria-serradora-boix-e1678457958767-1024x643.jpg 1024w, https:\/\/www.grupboix.com\/wp-content\/uploads\/2022\/11\/aeria-serradora-boix-e1678457958767-300x188.jpg 300w, https:\/\/www.grupboix.com\/wp-content\/uploads\/2022\/11\/aeria-serradora-boix-e1678457958767-768x482.jpg 768w, https:\/\/www.grupboix.com\/wp-content\/uploads\/2022\/11\/aeria-serradora-boix-e1678457958767.jpg 1406w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-1796\" class=\"wp-caption-text\">Fase 1 i fase 2 a la superf\u00edcie de la planta de producci\u00f3n del Saltet. Fuente: Grup Boix<\/figcaption><\/figure>\n<p>En este mismo sentido, el proyecto compone una tercera y \u00faltima fase que ampliar\u00e1 la instalaci\u00f3n hasta tener m\u00e1s de 3.400 paneles, que permitir\u00e1n satisfacer la demanda de consumo energ\u00e9tico para las actividades industriales del centro.<\/p>\n<p>Dentro de la circularidad de Grup Boix, desde el a\u00f1o 2004, la empresa trabaja para introducir nuevos modelos de consumos sostenibles y respetuosos con el medio ambiente. La implantaci\u00f3n de una caldera de biomasa, alimentada por la propia materia prima producida en la empresa, fue la primera apuesta para ahorrar energ\u00e9ticamente parte de la actividad industrial. Hoy en d\u00eda, la empresa cumple con el c\u00e1lculo de la huella de carbono en todas sus actividades industriales, con sistemas de gesti\u00f3n ambiental certificados como la ISO 14001, con el sello de consumo y producci\u00f3n responsable PEFC y la contrataci\u00f3n de empresas locales para reducir el impacto ambiental.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grup Boix instala 1.336 paneles fotovoltaicos en el centro de producci\u00f3n del Saltet, Puig-reig, en el marco del proyecto de autoabastecimiento energ\u00e9tico. El proyecto, financiado por el fondo Next Generation EU dentro del Plan de recuperaci\u00f3n, transformaci\u00f3n y resiliencia, forma parte de la estrategia de la empresa para consumir y producir energ\u00eda 100% renovable. Con [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1798,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74],"tags":[],"class_list":["post-2130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grup-boix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ampliaci\u00f3n de la planta solar fotovoltaica del centro de producci\u00f3n de Saltet - Grup Boix<\/title>\n<meta name=\"description\" content=\"Grup Boix instala 1.336 paneles fotovoltaicos en el centro de producci\u00f3n del Saltet en el marco del proyecto de autoabastecimiento energ\u00e9tico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ampliaci\u00f3n de la planta solar fotovoltaica del centro de producci\u00f3n de Saltet - Grup Boix\" \/>\n<meta property=\"og:description\" content=\"Grup Boix instala 1.336 paneles fotovoltaicos en el centro de producci\u00f3n del Saltet en el marco del proyecto de autoabastecimiento energ\u00e9tico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/\" \/>\n<meta property=\"og:site_name\" content=\"Grup Boix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/serradoraboix\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-10T14:21:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T12:02:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grupboix.com\/wp-content\/uploads\/2022\/11\/aeria-serradora-boix-e1678457958767.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SalviM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@serradoraboix\" \/>\n<meta name=\"twitter:site\" content=\"@serradoraboix\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"SalviM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.grupboix.com\\\/es\\\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupboix.com\\\/es\\\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\\\/\"},\"author\":{\"name\":\"SalviM\",\"@id\":\"https:\\\/\\\/www.grupboix.com\\\/#\\\/schema\\\/person\\\/282ab5532bc4ce63387493640bb551f6\"},\"headline\":\"Ampliaci\u00f3n de la planta solar fotovoltaica del centro de producci\u00f3n de Saltet\",\"datePublished\":\"2023-03-10T14:21:17+00:00\",\"dateModified\":\"2026-04-29T12:02:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.grupboix.com\\\/es\\\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\\\/\"},\"wordCount\":298,\"image\":{\"@id\":\"https:\\\/\\\/www.grupboix.com\\\/es\\\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupboix.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/aeria-serradora-boix-e1678457958767.jpg\",\"articleSection\":[\"Grup Boix\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.grupboix.com\\\/es\\\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\\\/\",\"url\":\"https:\\\/\\\/www.grupboix.com\\\/es\\\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\\\/\",\"name\":\"Ampliaci\u00f3n de la planta solar fotovoltaica del centro de producci\u00f3n de Saltet - Grup Boix\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.grupboix.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.grupboix.com\\\/es\\\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.grupboix.com\\\/es\\\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.grupboix.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/aeria-serradora-boix-e1678457958767.jpg\",\"datePublished\":\"2023-03-10T14:21:17+00:00\",\"dateModified\":\"2026-04-29T12:02:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.grupboix.com\\\/#\\\/schema\\\/person\\\/282ab5532bc4ce63387493640bb551f6\"},\"description\":\"Grup Boix instala 1.336 paneles fotovoltaicos en el centro de producci\u00f3n del Saltet en el marco del proyecto de autoabastecimiento energ\u00e9tico.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.grupboix.com\\\/es\\\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.grupboix.com\\\/es\\\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.grupboix.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/aeria-serradora-boix-e1678457958767.jpg\",\"contentUrl\":\"https:\\\/\\\/www.grupboix.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/aeria-serradora-boix-e1678457958767.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.grupboix.com\\\/#website\",\"url\":\"https:\\\/\\\/www.grupboix.com\\\/\",\"name\":\"Grup Boix\",\"description\":\"Fusta avui, bosc per sempre! Assegurar la protecci\u00f3, la regeneraci\u00f3 i la superviv\u00e8ncia dels boscos per millorar la seva capacitat d\u2019adaptaci\u00f3 i mantenir la biodiversitat\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.grupboix.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.grupboix.com\\\/#\\\/schema\\\/person\\\/282ab5532bc4ce63387493640bb551f6\",\"name\":\"SalviM\",\"url\":\"https:\\\/\\\/www.grupboix.com\\\/es\\\/author\\\/gb_salvi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ampliaci\u00f3n de la planta solar fotovoltaica del centro de producci\u00f3n de Saltet - Grup Boix","description":"Grup Boix instala 1.336 paneles fotovoltaicos en el centro de producci\u00f3n del Saltet en el marco del proyecto de autoabastecimiento energ\u00e9tico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/","og_locale":"es_ES","og_type":"article","og_title":"Ampliaci\u00f3n de la planta solar fotovoltaica del centro de producci\u00f3n de Saltet - Grup Boix","og_description":"Grup Boix instala 1.336 paneles fotovoltaicos en el centro de producci\u00f3n del Saltet en el marco del proyecto de autoabastecimiento energ\u00e9tico.","og_url":"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/","og_site_name":"Grup Boix","article_publisher":"https:\/\/www.facebook.com\/serradoraboix","article_published_time":"2023-03-10T14:21:17+00:00","article_modified_time":"2026-04-29T12:02:39+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.grupboix.com\/wp-content\/uploads\/2022\/11\/aeria-serradora-boix-e1678457958767.jpg","type":"image\/jpeg"}],"author":"SalviM","twitter_card":"summary_large_image","twitter_creator":"@serradoraboix","twitter_site":"@serradoraboix","twitter_misc":{"Escrito por":"SalviM","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/#article","isPartOf":{"@id":"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/"},"author":{"name":"SalviM","@id":"https:\/\/www.grupboix.com\/#\/schema\/person\/282ab5532bc4ce63387493640bb551f6"},"headline":"Ampliaci\u00f3n de la planta solar fotovoltaica del centro de producci\u00f3n de Saltet","datePublished":"2023-03-10T14:21:17+00:00","dateModified":"2026-04-29T12:02:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/"},"wordCount":298,"image":{"@id":"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupboix.com\/wp-content\/uploads\/2022\/11\/aeria-serradora-boix-e1678457958767.jpg","articleSection":["Grup Boix"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/","url":"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/","name":"Ampliaci\u00f3n de la planta solar fotovoltaica del centro de producci\u00f3n de Saltet - Grup Boix","isPartOf":{"@id":"https:\/\/www.grupboix.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/#primaryimage"},"image":{"@id":"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupboix.com\/wp-content\/uploads\/2022\/11\/aeria-serradora-boix-e1678457958767.jpg","datePublished":"2023-03-10T14:21:17+00:00","dateModified":"2026-04-29T12:02:39+00:00","author":{"@id":"https:\/\/www.grupboix.com\/#\/schema\/person\/282ab5532bc4ce63387493640bb551f6"},"description":"Grup Boix instala 1.336 paneles fotovoltaicos en el centro de producci\u00f3n del Saltet en el marco del proyecto de autoabastecimiento energ\u00e9tico.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.grupboix.com\/es\/ampliacio-de-la-planta-solar-fotovoltaica-del-centre-de-produccio-del-saltet\/#primaryimage","url":"https:\/\/www.grupboix.com\/wp-content\/uploads\/2022\/11\/aeria-serradora-boix-e1678457958767.jpg","contentUrl":"https:\/\/www.grupboix.com\/wp-content\/uploads\/2022\/11\/aeria-serradora-boix-e1678457958767.jpg","width":1920,"height":1080},{"@type":"WebSite","@id":"https:\/\/www.grupboix.com\/#website","url":"https:\/\/www.grupboix.com\/","name":"Grup Boix","description":"Fusta avui, bosc per sempre! Assegurar la protecci\u00f3, la regeneraci\u00f3 i la superviv\u00e8ncia dels boscos per millorar la seva capacitat d\u2019adaptaci\u00f3 i mantenir la biodiversitat","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grupboix.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.grupboix.com\/#\/schema\/person\/282ab5532bc4ce63387493640bb551f6","name":"SalviM","url":"https:\/\/www.grupboix.com\/es\/author\/gb_salvi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.grupboix.com\/es\/wp-json\/wp\/v2\/posts\/2130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grupboix.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grupboix.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grupboix.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grupboix.com\/es\/wp-json\/wp\/v2\/comments?post=2130"}],"version-history":[{"count":4,"href":"https:\/\/www.grupboix.com\/es\/wp-json\/wp\/v2\/posts\/2130\/revisions"}],"predecessor-version":[{"id":3005,"href":"https:\/\/www.grupboix.com\/es\/wp-json\/wp\/v2\/posts\/2130\/revisions\/3005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grupboix.com\/es\/wp-json\/wp\/v2\/media\/1798"}],"wp:attachment":[{"href":"https:\/\/www.grupboix.com\/es\/wp-json\/wp\/v2\/media?parent=2130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grupboix.com\/es\/wp-json\/wp\/v2\/categories?post=2130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grupboix.com\/es\/wp-json\/wp\/v2\/tags?post=2130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}